{"id":2598,"date":"2022-03-01T14:34:45","date_gmt":"2022-03-01T14:34:45","guid":{"rendered":"https:\/\/hertog.t2m.dev\/?page_id=2598"},"modified":"2023-04-14T08:39:13","modified_gmt":"2023-04-14T08:39:13","slug":"our-gradings","status":"publish","type":"page","link":"https:\/\/www.hertog.com\/en\/our-specialties\/our-gradings\/","title":{"rendered":"Our gradings"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;70&#8243; top_padding_tablet=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;138&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;image-XL-left-top&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h5>Designed by Hertog<\/h5>\n<h1>Our gradings<\/h1>\n[\/vc_column_text][vc_column_text el_class=&#8221;text-small&#8221;]Wood naturally has knots, cracks and color shades. The grading indicates how rustic your floor is. From knot-free to very rustic. In our collections you can see in which grades this floor is available.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;120&#8243; bottom_padding=&#8221;120&#8243; top_padding_tablet=&#8221;90&#8243; bottom_padding_tablet=&#8221;90&#8243; top_padding_phone=&#8221;70&#8243; bottom_padding_phone=&#8221;70&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;3895,3883,3887,3891,3879,3875&#8243; image_grid_loading=&#8221;default&#8221; display_title_caption=&#8221;true&#8221; layout=&#8221;4&#8243; item_spacing=&#8221;20px&#8221; gallery_style=&#8221;5&#8243; load_in_animation=&#8221;none&#8221; img_size=&#8221;400&#215;850&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"templatera_shortcode\">\n\t\t<div id=\"fws_6a982972ad145\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-section  zindex-set top_padding_tablet_120px top_padding_phone_90px bottom_padding_tablet_120px bottom_padding_phone_90px\"  style=\"padding-top: 150px; padding-bottom: 150px;  z-index: 200;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #2c2a2a; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2>Inspiration<\/h2>\n\t<\/div>\n<\/div>\n\n\n\n\n\t<div class=\"wpb_gallery wpb_content_element clearfix\">\n\t\t<div class=\"wpb_wrapper\"><div class=\"wpb_gallery_slidesflickity_static_height_style\" data-onclick=\"link_no\" data-interval=\"5\"><style>.wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a982972aee04:not(.masonry) .flickity-slider .cell img {\n      height: 600px;\n    }\n    @media only screen and (max-width: 1300px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a982972aee04:not(.masonry) .flickity-slider .cell img {\n        height: 400px;\n      }\n    }\n    @media only screen and (max-width: 1000px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a982972aee04:not(.masonry) .flickity-slider .cell img {\n        height: 350px;\n      }\n    }\n    @media only screen and (max-width: 690px) {\n      .wpb_gallery_slidesflickity_static_height_style .nectar-flickity.instace-6a982972aee04:not(.masonry) .flickity-slider .cell img {\n        height: 300px;\n      }\n    }<\/style><div class=\"nectar-flickity not-initialized instace-6a982972aee04 drag-indicator-only\" data-indicator-bg=\"#c59c4f\" data-indicator-icon=\"#ffffff\"  data-touch-icon-color=\"default\" data-drag-scale=\"\" data-overflow=\"visible\" data-wrap=\"no-wrap\" data-spacing=\"10px\" data-shadow=\"none\" data-autoplay=\"\" data-autoplay-dur=\"\" data-free-scroll=\"true\" data-controls=\"touch_total\"><div class=\"flickity-viewport\"> <div class=\"flickity-slider\"><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><\/div><\/div><\/div><\/div><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"1000\" src=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-2.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-2.jpg 665w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-2-300x450.jpg 300w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-2-600x902.jpg 600w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-2-200x300.jpg 200w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/div><\/div><\/div><\/div><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"790\" height=\"515\" src=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-3.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-3.jpg 790w, https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-3-600x391.jpg 600w, https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-3-300x196.jpg 300w, https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-3-768x501.jpg 768w\" sizes=\"auto, (max-width: 790px) 100vw, 790px\" \/><\/div><\/div><\/div><\/div><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"830\" height=\"670\" src=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Hertog-Kleuren-header-1.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Hertog-Kleuren-header-1.jpg 830w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Hertog-Kleuren-header-1-600x484.jpg 600w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Hertog-Kleuren-header-1-300x242.jpg 300w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Hertog-Kleuren-header-1-768x620.jpg 768w\" sizes=\"auto, (max-width: 830px) 100vw, 830px\" \/><\/div><\/div><\/div><\/div><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"570\" src=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-2.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-2.jpg 630w, https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-2-600x543.jpg 600w, https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-2-300x271.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/div><\/div><\/div><\/div><div class=\"cell\" data-lazy=\"false\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-1.15\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><div class=\"img-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"665\" src=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-8-1.jpg\" class=\"skip-lazy nectar-lazy attachment-large\" alt=\"\" srcset=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-8-1.jpg 1000w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-8-1-600x399.jpg 600w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-8-1-300x200.jpg 300w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-8-1-768x511.jpg 768w, https:\/\/www.hertog.com\/wp-content\/uploads\/2022\/01\/Interieur-Marinje-8-1-900x600.jpg 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"templatera_shortcode\">\n\t\t<div id=\"fws_6a982972b21ef\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top bg-floor-2\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a982972b2cba\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-5 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap \" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy \" data-delay=\"0\" height=\"520\" width=\"550\" data-animation=\"none\" src=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-5.jpg\" alt=\"\" srcset=\"https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-5.jpg 550w, https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-5-300x284.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  color-1\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h6>Why Hertog<\/h6>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3>3 reasons to<br \/>\nchoose Hertog<\/h3>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-check\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-2\" data-spacing=\"default\" data-alignment=\"left\"> \r\n<ul>\r\n \t<li>Trendy and timeless designs<\/li>\r\n \t<li>Go for character floors<\/li>\r\n \t<li>Durable floors guaranteed<\/li>\r\n<\/ul>\r\n <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a982972b509b\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  top_padding_tablet_100px top_padding_phone_60px bottom_padding_tablet_100px bottom_padding_phone_60px\"  style=\"padding-top: 150px; padding-bottom: 150px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a982972b6dfd\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\"\" class=\"vc_col-sm-7 wpb_column column_container vc_column_container col child_column padding-5-percent inherit_tablet inherit_phone \"  data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#2c2a2a\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #2c2a2a;\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  color-1\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h6>Come and see our floors!<\/h6>\n\t<\/div>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2>Find a point of sale<br \/>\nnearby<\/h2>\n\t<\/div>\n<\/div>\n\n\n\n<a class=\"nectar-button large regular extra-color-3  regular-button\"  style=\"margin-top: 20px; color: #2c2a2a; \"  href=\"\/en\/store-locator\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>View points of sale<\/span><\/a>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div style=\"\" class=\"vc_col-sm-5 image-L-right-bottom wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone \"  data-using-bg=\"true\" data-bg-cover=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap viewport-desktop\" data-bg-pos=\"right center\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg\" style=\" background-image: url('https:\/\/www.hertog.com\/wp-content\/uploads\/2021\/12\/Hertog-home-img-6.jpg'); \"><\/div><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"Designed by Hertog Our gradings Wood naturally has knots, cracks and color shades. The grading indicates how rustic your floor is. From knot-free to very rustic. In our collections you...","protected":false},"author":1,"featured_media":0,"parent":2559,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2598","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hertog.com\/en\/wp-json\/wp\/v2\/pages\/2598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hertog.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hertog.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hertog.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hertog.com\/en\/wp-json\/wp\/v2\/comments?post=2598"}],"version-history":[{"count":4,"href":"https:\/\/www.hertog.com\/en\/wp-json\/wp\/v2\/pages\/2598\/revisions"}],"predecessor-version":[{"id":4424,"href":"https:\/\/www.hertog.com\/en\/wp-json\/wp\/v2\/pages\/2598\/revisions\/4424"}],"up":[{"embeddable":true,"href":"https:\/\/www.hertog.com\/en\/wp-json\/wp\/v2\/pages\/2559"}],"wp:attachment":[{"href":"https:\/\/www.hertog.com\/en\/wp-json\/wp\/v2\/media?parent=2598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}